{"id":14381,"date":"2024-06-18T12:46:52","date_gmt":"2024-06-18T12:46:52","guid":{"rendered":"https:\/\/aedcolor.com\/?page_id=14381"},"modified":"2024-06-18T12:46:52","modified_gmt":"2024-06-18T12:46:52","slug":"isomat-ak-24-crystal-gel","status":"publish","type":"page","link":"https:\/\/aedcolor.com\/index.php\/isomat-ak-24-crystal-gel\/","title":{"rendered":"ISOMAT AK-24 CRYSTAL GEL"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1683099634441{padding-bottom: 30px !important;}&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_custom_heading text=&#8221;ISOMAT AK-24 CRYSTAL GEL&#8221; font_container=&#8221;tag:h2|font_size:50|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; link=&#8221;|title:AQUAMAT%20-%20SUPERELASTIC||&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;14379&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<span style=\"color: #000000;\"><strong>I formuluar me ekspertize me tekonologjine inovative Crystal Gel te ISOMAT, ai ngurtesohet per nje kohe me te shpejte se sa ngjites tradicional (3-6 ore), pavaresisht nga sezoni, duke pershpejtuar perfundimin e projektit.<\/strong> Nuk siguron rreshqitje vertikale edhe ne temperatura te larta. Plus, fale konsistences\u00a0 se tij kremoze, siguron punueshmeri te jashtezakonshme dhe aplikim te lehte.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Vetite e xhelit<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">Bazuar ne polimere te fryre nga uji, ISOMAT AK-24 CRYSTAL GEL ka veti novatore kryesisht per sa i perket lehtesise se aplikimit, lagshmerise dhe ngjitjes ne nenshtresa dhe pllaka. Konsistenca e tij e lemuar dhe kremoze siguron punueshmeri te shkelqyer dhe perhapje me te lehte, ndersa formulimi i tij tiksotrop pa rreshqitje vertikale garanton nje aplikim te suksesshem ne mure.\u00a0<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Fusha e Aplikimit<\/span><\/strong><br \/>\n<span style=\"color: #000000;\">Per fiksimin e pllakave absorbuese dhe jo absorbuese te murit dhe dyshemese, duke perfshire gurin natyral, tulla dekorative dhe pllaka me format te madh, ne nje sere nenshtresash, veacnerisht kur ka ngjitje te larte, fleksibiliteti shtese dhe rezistence ndaj lageshtires (p.sh. pllaka te vjetra, ballkone, derrasa gispi, dysheme me ngrohje etj.) Per perdorime te brendshme dhe te jashtme.<\/span>[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"standard-arrow bullet-top\"><ul>\n<li><span style=\"color: #000000;\">Per shkak te permbajtjes se cimentos, produkti reagon me ujin, duke formuar solucion alkaline dhe keshtu klasifikohet si irritues.<\/span><\/li>\n<li><span style=\"color: #000000;\">Siperfaqet shume poroze, si betoni i gazuar, derrasa gipsi etj. duhet te shtrohen me astar akrilik UNI-PRIMER ose FLEXPRIMER.<\/span><\/li>\n<\/ul>\n<\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"standard-arrow bullet-top\"><ul>\n<li><span style=\"color: #000000;\">Afati i ruajtjes: 12 muaj nga data e prodhimit, ruhet ne ambalazh origjinal, te mbyllur, ne kushte te thata dhe pa ngrica.<\/span><\/li>\n<\/ul>\n<\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1683100048912{padding-top: 20px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-5123\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:65px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/aedcolor.com\/wp-content\/uploads\/2023\/05\/image-2.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5123 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Sip\u00ebrfaqe: Beton, pllake<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-6909\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:65px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/aedcolor.com\/wp-content\/uploads\/2023\/05\/image-1.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-6909 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Aplikimi: Me mistri<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1683099634441{padding-bottom: 30px !important;}&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_custom_heading text=&#8221;ISOMAT AK-24 CRYSTAL GEL&#8221; font_container=&#8221;tag:h2|font_size:50|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; link=&#8221;|title:AQUAMAT%20-%20SUPERELASTIC||&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;14379&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]I formuluar me ekspertize me tekonologjine inovative Crystal Gel te ISOMAT, ai ngurtesohet per nje kohe me te shpejte se sa ngjites tradicional (3-6 ore), pavaresisht nga sezoni, duke pershpejtuar perfundimin e projektit. Nuk siguron rreshqitje vertikale edhe ne&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14381","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/pages\/14381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/comments?post=14381"}],"version-history":[{"count":1,"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/pages\/14381\/revisions"}],"predecessor-version":[{"id":14383,"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/pages\/14381\/revisions\/14383"}],"wp:attachment":[{"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/media?parent=14381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}