{"id":2044,"date":"2023-05-08T09:14:09","date_gmt":"2023-05-08T09:14:09","guid":{"rendered":"https:\/\/aedcolor.com\/?page_id=2044"},"modified":"2023-06-07T12:47:35","modified_gmt":"2023-06-07T12:47:35","slug":"smaltox-mono","status":"publish","type":"page","link":"https:\/\/aedcolor.com\/index.php\/smaltox-mono\/","title":{"rendered":"SMALTOX MONO"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1683099634441{padding-bottom: 30px !important;}&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_custom_heading text=&#8221;SMALTOX MONO<\/p>\n<p>&#8221; font_container=&#8221;tag:h2|font_size:50|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; link=&#8221;|title:AQUAMAT%20-%20SUPERELASTIC||&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;2045&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"order-md-0 py-md-3 font-weight-bold text-sm-left\">\n<div class=\"clearfix text-formatted field field--name-body field--type-text-with-summary field--label-hidden field__item\">\n<p><strong>Astar akrilik i bardh\u00eb p\u00ebr aplikime t\u00eb ve\u00e7anta me ngjitje t\u00eb shk\u00eblqyer. <\/strong><\/p>\n<p>E p\u00ebrshtatshme p\u00ebr p\u00ebrdorim t\u00eb brendsh\u00ebm dhe t\u00eb jasht\u00ebm.<\/p>\n<\/div>\n<\/div>\n<div class=\"order-md-1 row no-gutters pb-3 pb-md-0\">\n<div class=\"col-12 col-xs-6 col-sm-12 col-md-6 d-flex pb-2 pb-md-3 \"><\/div>\n<\/div>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"standard-arrow bullet-top\"><ul>\n<li>\n<div class=\"col-12 col-xs-6 col-sm-12 col-md-6 d-flex pb-2 pb-md-3 \">\n<div>Izolon papast\u00ebrtit\u00eb dhe njollat<\/div>\n<\/div>\n<\/li>\n<li>Thahet shpejt<\/li>\n<li>Dep\u00ebrtim i lart\u00eb<\/li>\n<\/ul>\n<\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"standard-arrow bullet-top\"><ul>\n<li>P\u00ebrmbajtje e ul\u00ebt e VOC-ve<\/li>\n<li>Ngjitje e shk\u00eblqyer<\/li>\n<li>Ideale p\u00ebr lyerjen e sip\u00ebrfaqeve t\u00eb lyera<\/li>\n<\/ul>\n<\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1683100048912{padding-top: 20px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3649\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:65px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/aedcolor.com\/wp-content\/uploads\/2023\/05\/image-2.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3649 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Sip\u00ebrfaqe: Muri<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3950\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:65px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/aedcolor.com\/wp-content\/uploads\/2023\/05\/image-1.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3950 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Aplikimi: P\u00ebrgatitja<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;ex-full&#8221; bg_color_value=&#8221;rgba(237,237,237,0.9)&#8221;][vc_column][vc_custom_heading text=&#8221;MJETET:&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;ex-full&#8221; bg_color_value=&#8221;rgba(237,237,237,0.9)&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component   ic2_class style_1\"><div id=\"Info-box-wrap-1436\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:50px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/aedcolor.com\/wp-content\/uploads\/2023\/06\/paintbrush.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-1436 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Penel<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component   ic2_class style_1\"><div id=\"Info-box-wrap-5211\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:48px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/aedcolor.com\/wp-content\/uploads\/2023\/06\/spray-gun.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5211 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Pistolet\u00eb sp\u00ebrkat\u00ebse pa aj\u00ebr<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component   ic2_class style_1\"><div id=\"Info-box-wrap-9448\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:50px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/aedcolor.com\/wp-content\/uploads\/2023\/06\/paint-roller-1.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-9448 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Rul<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][vc_custom_heading text=&#8221;PAKETIMI:&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"aio-icon-component   ic_class style_1\"><div id=\"Info-box-wrap-9446\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-9446 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">750 ml, 2,5 lt<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1686141769939{padding-top: 30px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Karakteristikat teknike&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;]<div class=\"ult-spacer spacer-6a045dba3e9e4\" data-id=\"6a045dba3e9e4\" data-height=\"20\" data-height-mobile=\"20\" data-height-tab=\"20\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component   ic3_class style_1\"><div id=\"Info-box-wrap-1087\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:50px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/aedcolor.com\/wp-content\/uploads\/2023\/06\/water-waves.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-1087 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">HOLLIM<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-1087 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">10-20% me Smaltolux White Spirit<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component   ic3_class style_1\"><div id=\"Info-box-wrap-4686\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:50px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/aedcolor.com\/wp-content\/uploads\/2023\/06\/paint-bucket-1.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4686 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">FUQIA MBULUESE<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-4686 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">8-10 (m\u00b2\/Lt)<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component   ic3_class style_1\"><div id=\"Info-box-wrap-8286\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:50px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/aedcolor.com\/wp-content\/uploads\/2023\/06\/painting.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-8286 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">SHTRESAT<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-8286 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">1<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1683099634441{padding-bottom: 30px !important;}&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_custom_heading text=&#8221;SMALTOX MONO &#8221; font_container=&#8221;tag:h2|font_size:50|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; link=&#8221;|title:AQUAMAT%20-%20SUPERELASTIC||&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;2045&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Astar akrilik i bardh\u00eb p\u00ebr aplikime t\u00eb ve\u00e7anta me ngjitje t\u00eb shk\u00eblqyer. E p\u00ebrshtatshme p\u00ebr p\u00ebrdorim t\u00eb brendsh\u00ebm dhe t\u00eb jasht\u00ebm. [\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1683100048912{padding-top: 20px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;ex-full&#8221; bg_color_value=&#8221;rgba(237,237,237,0.9)&#8221;][vc_column][vc_custom_heading text=&#8221;MJETET:&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;ex-full&#8221; bg_color_value=&#8221;rgba(237,237,237,0.9)&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2044","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/pages\/2044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/comments?post=2044"}],"version-history":[{"count":3,"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/pages\/2044\/revisions"}],"predecessor-version":[{"id":4362,"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/pages\/2044\/revisions\/4362"}],"wp:attachment":[{"href":"https:\/\/aedcolor.com\/index.php\/wp-json\/wp\/v2\/media?parent=2044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}